{"id":430,"count":1,"description":"","link":"https:\/\/abconcretedesign.com\/hu\/tag\/wood-hu\/","name":"wood","slug":"wood-hu","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>H\u00edreink, munk\u00e1ink wood t\u00e9mak\u00f6rben &#187; AB Concrete Design<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"wood Arch\u00edvum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abconcretedesign.com\/hu\/tag\/wood-hu\/\" \/>\n<meta property=\"og:site_name\" content=\"AB Concrete Design\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abconcretedesign.com\/wp-content\/uploads\/2019\/10\/business-gift-collection-ab-concrete-design.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/tag\\\/wood-hu\\\/\",\"url\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/tag\\\/wood-hu\\\/\",\"name\":\"H\u00edreink, munk\u00e1ink wood t\u00e9mak\u00f6rben &#187; AB Concrete Design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/tag\\\/wood-hu\\\/#breadcrumb\"},\"inLanguage\":\"hu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/tag\\\/wood-hu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"F\u0151oldal\",\"item\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"wood\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/#website\",\"url\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/\",\"name\":\"AB Concrete Design and Business Gifts\",\"description\":\"Beton Design T\u00e1rgyak, \u00c9kszer \u00e9s \u00dczleti Aj\u00e1nd\u00e9k, Beton Tr\u00f3fe\u00e1k\",\"publisher\":{\"@id\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/#organization\",\"name\":\"AB Concrete Design\",\"url\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abconcretedesign.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/ab-concrete-design-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/abconcretedesign.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/ab-concrete-design-logo.jpg\",\"width\":351,\"height\":89,\"caption\":\"AB Concrete Design\"},\"image\":{\"@id\":\"https:\\\/\\\/abconcretedesign.com\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"H\u00edreink, munk\u00e1ink wood t\u00e9mak\u00f6rben &#187; AB Concrete Design","robots":{"index":"noindex","follow":"follow"},"og_locale":"hu_HU","og_type":"article","og_title":"wood Arch\u00edvum","og_url":"https:\/\/abconcretedesign.com\/hu\/tag\/wood-hu\/","og_site_name":"AB Concrete Design","og_image":[{"width":1600,"height":1068,"url":"https:\/\/abconcretedesign.com\/wp-content\/uploads\/2019\/10\/business-gift-collection-ab-concrete-design.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/abconcretedesign.com\/hu\/tag\/wood-hu\/","url":"https:\/\/abconcretedesign.com\/hu\/tag\/wood-hu\/","name":"H\u00edreink, munk\u00e1ink wood t\u00e9mak\u00f6rben &#187; AB Concrete Design","isPartOf":{"@id":"https:\/\/abconcretedesign.com\/hu\/#website"},"breadcrumb":{"@id":"https:\/\/abconcretedesign.com\/hu\/tag\/wood-hu\/#breadcrumb"},"inLanguage":"hu"},{"@type":"BreadcrumbList","@id":"https:\/\/abconcretedesign.com\/hu\/tag\/wood-hu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"F\u0151oldal","item":"https:\/\/abconcretedesign.com\/hu\/"},{"@type":"ListItem","position":2,"name":"wood"}]},{"@type":"WebSite","@id":"https:\/\/abconcretedesign.com\/hu\/#website","url":"https:\/\/abconcretedesign.com\/hu\/","name":"AB Concrete Design and Business Gifts","description":"Beton Design T\u00e1rgyak, \u00c9kszer \u00e9s \u00dczleti Aj\u00e1nd\u00e9k, Beton Tr\u00f3fe\u00e1k","publisher":{"@id":"https:\/\/abconcretedesign.com\/hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abconcretedesign.com\/hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/abconcretedesign.com\/hu\/#organization","name":"AB Concrete Design","url":"https:\/\/abconcretedesign.com\/hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/abconcretedesign.com\/hu\/#\/schema\/logo\/image\/","url":"https:\/\/abconcretedesign.com\/wp-content\/uploads\/2019\/04\/ab-concrete-design-logo.jpg","contentUrl":"https:\/\/abconcretedesign.com\/wp-content\/uploads\/2019\/04\/ab-concrete-design-logo.jpg","width":351,"height":89,"caption":"AB Concrete Design"},"image":{"@id":"https:\/\/abconcretedesign.com\/hu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/abconcretedesign.com\/hu\/wp-json\/wp\/v2\/tags\/430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abconcretedesign.com\/hu\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/abconcretedesign.com\/hu\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/abconcretedesign.com\/hu\/wp-json\/wp\/v2\/posts?tags=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}